{"id":5027,"date":"2026-02-22T15:20:00","date_gmt":"2026-02-22T13:20:00","guid":{"rendered":"https:\/\/ziva-voda.com\/blog\/?p=5027"},"modified":"2026-05-10T15:21:26","modified_gmt":"2026-05-10T13:21:26","slug":"ucinki-prehrane-16-8-na-telesno-tezo","status":"publish","type":"post","link":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/","title":{"rendered":"U\u010dinki prehrane 16\/8 na telesno te\u017eo"},"content":{"rendered":"\n<p>Raziskave pri ljudeh so dosledno pokazale, da \u010dasovno omejevanje hranjenja zmanj\u0161uje dele\u017e ma\u0161\u010dobnega tkiva, v ve\u010dini raziskav se je tudi rahlo zni\u017eala previsoka telesna te\u017ea udele\u017eencev.<\/p>\n\n\n\n<p>Huj\u0161anje za nekatere ni potrebno ne za\u017eeleno. V tem smislu je pomembna raziskava, v kateri so dobro trenirane \u0161portnike z ustrezno telesno te\u017eo za osem tednov razdelili v dve skupini, ki sta u\u017eivali enako hrano, le da so v testni skupini omejili prehranjevanje na osem ur na dan, v drugi pa ni bilo \u010dasovnih omejitev. Povpre\u010dna starost \u0161portnikov je bila bil skoraj trideset let. Udele\u017eenci obeh skupin so v \u010dasu eksperimenta trenirali.<\/p>\n\n\n\n<p>Oboji so ohranili telesno te\u017eo, mi\u0161i\u010dna masa in telesna mo\u010d sta se pri obojih pove\u010dali, toda le pri \u0161portnikih, ki so omejevali \u010das prehranjevanja, se je zni\u017eal dele\u017e telesne ma\u0161\u010dobe (Moro et al., 2016).<\/p>\n\n\n\n<p>Vir:\u00a0<a href=\"https:\/\/www.institut-o.com\/prijateljem-najboljse-december-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">PRIJATELJEM NAJBOLJ\u0160E!<\/a><br><a href=\"https:\/\/www.institut-o.com\/prijateljem-najboljse-december-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">Novice za uporabnike FHES, OKA (angl. MAP) in probiotikov EM,<\/a><br><a href=\"https:\/\/www.institut-o.com\/prijateljem-najboljse-februar-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">FEBRUAR2026, Dr. Iztok Ostan<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Raziskave pri ljudeh so dosledno pokazale, da \u010dasovno omejevanje hranjenja zmanj\u0161uje dele\u017e ma\u0161\u010dobnega tkiva, v ve\u010dini raziskav se je tudi rahlo zni\u017eala previsoka telesna te\u017ea udele\u017eencev. Huj\u0161anje za nekatere ni potrebno ne za\u017eeleno. V tem smislu je pomembna raziskava, v kateri so dobro trenirane \u0161portnike z ustrezno telesno te\u017eo za osem tednov razdelili v dve [&hellip;]<\/p>\n","protected":false},"author":88890,"featured_media":5029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[8],"tags":[516,28],"class_list":["post-5027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raziskave","tag-postenje","tag-raziskava","et-has-post-format-content","et_post_format-et-post-format-standard"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>U\u010dinki Prehrane 16\/8 na Telesno Te\u017eo<\/title>\n<meta name=\"description\" content=\"mi\u0161i\u010dna masa in telesna mo\u010d sta se pri obojih pove\u010dali, toda le pri \u0161portnikih, ki so omejevali \u010das prehranjevanja,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"U\u010dinki Prehrane 16\/8 na Telesno Te\u017eo\" \/>\n<meta property=\"og:description\" content=\"mi\u0161i\u010dna masa in telesna mo\u010d sta se pri obojih pove\u010dali, toda le pri \u0161portnikih, ki so omejevali \u010das prehranjevanja,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/\" \/>\n<meta property=\"og:site_name\" content=\"\u017diva Voda Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/sl-si.facebook.com\/zivavoda.megahydrate\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-22T13:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T13:21:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ziva-voda.com\/blog\/wp-content\/uploads\/ucinki-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valerija Gad\u017ea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zivavoda\" \/>\n<meta name=\"twitter:site\" content=\"@zivavoda\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valerija Gad\u017ea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/\"},\"author\":{\"name\":\"Valerija Gad\u017ea\",\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/#\\\/schema\\\/person\\\/aa7e178a505b88f1295d4c7330a3ca22\"},\"headline\":\"U\u010dinki prehrane 16\\\/8 na telesno te\u017eo\",\"datePublished\":\"2026-02-22T13:20:00+00:00\",\"dateModified\":\"2026-05-10T13:21:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/\"},\"wordCount\":174,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/wp-content\\\/uploads\\\/ucinki-scaled.jpg\",\"keywords\":[\"postenje\",\"raziskava\"],\"articleSection\":[\"Raziskave\"],\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/\",\"url\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/\",\"name\":\"U\u010dinki Prehrane 16\\\/8 na Telesno Te\u017eo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/wp-content\\\/uploads\\\/ucinki-scaled.jpg\",\"datePublished\":\"2026-02-22T13:20:00+00:00\",\"dateModified\":\"2026-05-10T13:21:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/#\\\/schema\\\/person\\\/aa7e178a505b88f1295d4c7330a3ca22\"},\"description\":\"mi\u0161i\u010dna masa in telesna mo\u010d sta se pri obojih pove\u010dali, toda le pri \u0161portnikih, ki so omejevali \u010das prehranjevanja,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/wp-content\\\/uploads\\\/ucinki-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/wp-content\\\/uploads\\\/ucinki-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"ucinki\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/ucinki-prehrane-16-8-na-telesno-tezo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Domov\",\"item\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"U\u010dinki prehrane 16\\\/8 na telesno te\u017eo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/\",\"name\":\"\u017diva Voda Blog\",\"description\":\"Male Skrivnosti za Ve\u010d Energije in Bolj\u0161e Po\u010dutje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sl-SI\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ziva-voda.com\\\/blog\\\/#\\\/schema\\\/person\\\/aa7e178a505b88f1295d4c7330a3ca22\",\"name\":\"Valerija Gad\u017ea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cebd5464c4a2214b03add6684b9ab269f2299d88e88f958e78505be38365a8fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cebd5464c4a2214b03add6684b9ab269f2299d88e88f958e78505be38365a8fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cebd5464c4a2214b03add6684b9ab269f2299d88e88f958e78505be38365a8fb?s=96&d=mm&r=g\",\"caption\":\"Valerija Gad\u017ea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"U\u010dinki Prehrane 16\/8 na Telesno Te\u017eo","description":"mi\u0161i\u010dna masa in telesna mo\u010d sta se pri obojih pove\u010dali, toda le pri \u0161portnikih, ki so omejevali \u010das prehranjevanja,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/","og_locale":"sl_SI","og_type":"article","og_title":"U\u010dinki Prehrane 16\/8 na Telesno Te\u017eo","og_description":"mi\u0161i\u010dna masa in telesna mo\u010d sta se pri obojih pove\u010dali, toda le pri \u0161portnikih, ki so omejevali \u010das prehranjevanja,","og_url":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/","og_site_name":"\u017diva Voda Blog","article_publisher":"https:\/\/sl-si.facebook.com\/zivavoda.megahydrate","article_published_time":"2026-02-22T13:20:00+00:00","article_modified_time":"2026-05-10T13:21:26+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/ziva-voda.com\/blog\/wp-content\/uploads\/ucinki-scaled.jpg","type":"image\/jpeg"}],"author":"Valerija Gad\u017ea","twitter_card":"summary_large_image","twitter_creator":"@zivavoda","twitter_site":"@zivavoda","twitter_misc":{"Written by":"Valerija Gad\u017ea","Est. reading time":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/#article","isPartOf":{"@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/"},"author":{"name":"Valerija Gad\u017ea","@id":"https:\/\/ziva-voda.com\/blog\/#\/schema\/person\/aa7e178a505b88f1295d4c7330a3ca22"},"headline":"U\u010dinki prehrane 16\/8 na telesno te\u017eo","datePublished":"2026-02-22T13:20:00+00:00","dateModified":"2026-05-10T13:21:26+00:00","mainEntityOfPage":{"@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/"},"wordCount":174,"commentCount":0,"image":{"@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/#primaryimage"},"thumbnailUrl":"https:\/\/ziva-voda.com\/blog\/wp-content\/uploads\/ucinki-scaled.jpg","keywords":["postenje","raziskava"],"articleSection":["Raziskave"],"inLanguage":"sl-SI","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/","url":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/","name":"U\u010dinki Prehrane 16\/8 na Telesno Te\u017eo","isPartOf":{"@id":"https:\/\/ziva-voda.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/#primaryimage"},"image":{"@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/#primaryimage"},"thumbnailUrl":"https:\/\/ziva-voda.com\/blog\/wp-content\/uploads\/ucinki-scaled.jpg","datePublished":"2026-02-22T13:20:00+00:00","dateModified":"2026-05-10T13:21:26+00:00","author":{"@id":"https:\/\/ziva-voda.com\/blog\/#\/schema\/person\/aa7e178a505b88f1295d4c7330a3ca22"},"description":"mi\u0161i\u010dna masa in telesna mo\u010d sta se pri obojih pove\u010dali, toda le pri \u0161portnikih, ki so omejevali \u010das prehranjevanja,","breadcrumb":{"@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/"]}]},{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/#primaryimage","url":"https:\/\/ziva-voda.com\/blog\/wp-content\/uploads\/ucinki-scaled.jpg","contentUrl":"https:\/\/ziva-voda.com\/blog\/wp-content\/uploads\/ucinki-scaled.jpg","width":2560,"height":1707,"caption":"ucinki"},{"@type":"BreadcrumbList","@id":"https:\/\/ziva-voda.com\/blog\/ucinki-prehrane-16-8-na-telesno-tezo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Domov","item":"https:\/\/ziva-voda.com\/blog\/"},{"@type":"ListItem","position":2,"name":"U\u010dinki prehrane 16\/8 na telesno te\u017eo"}]},{"@type":"WebSite","@id":"https:\/\/ziva-voda.com\/blog\/#website","url":"https:\/\/ziva-voda.com\/blog\/","name":"\u017diva Voda Blog","description":"Male Skrivnosti za Ve\u010d Energije in Bolj\u0161e Po\u010dutje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ziva-voda.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sl-SI"},{"@type":"Person","@id":"https:\/\/ziva-voda.com\/blog\/#\/schema\/person\/aa7e178a505b88f1295d4c7330a3ca22","name":"Valerija Gad\u017ea","image":{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/secure.gravatar.com\/avatar\/cebd5464c4a2214b03add6684b9ab269f2299d88e88f958e78505be38365a8fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cebd5464c4a2214b03add6684b9ab269f2299d88e88f958e78505be38365a8fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cebd5464c4a2214b03add6684b9ab269f2299d88e88f958e78505be38365a8fb?s=96&d=mm&r=g","caption":"Valerija Gad\u017ea"}}]}},"_links":{"self":[{"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/posts\/5027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/users\/88890"}],"replies":[{"embeddable":true,"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/comments?post=5027"}],"version-history":[{"count":1,"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/posts\/5027\/revisions"}],"predecessor-version":[{"id":5028,"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/posts\/5027\/revisions\/5028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/media\/5029"}],"wp:attachment":[{"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/media?parent=5027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/categories?post=5027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ziva-voda.com\/blog\/wp-json\/wp\/v2\/tags?post=5027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}